{"id":17214,"date":"2025-08-21T06:00:00","date_gmt":"2025-08-21T04:00:00","guid":{"rendered":"https:\/\/grain-dpixel.fr\/info\/?p=17214"},"modified":"2025-08-15T07:40:45","modified_gmt":"2025-08-15T05:40:45","slug":"inteview-delodie-jarrier","status":"publish","type":"post","link":"https:\/\/grain-dpixel.fr\/info\/inteview-delodie-jarrier\/","title":{"rendered":"Inteview d&rsquo;\u00c9lodie JARRIER"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-text-align-center\">Exposition aux Invit\u00e9s au festin, du 4 au 26 octobre<\/h3>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Du lundi au vendredi de 13h30 \u00e0 16h30<br>Dimanche 4, 11 et 25 octobre de 14h00 \u00e0 16h00<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><i><strong>&#8211; Quelques mots pour te pr\u00e9senter :<\/strong><\/i><br>J\u2019ai 42 ans. Je suis n\u00e9e \u00e0 Paray-le-Monial (Sa\u00f4ne et Loire), et je r\u00e9side \u00e0 Dijon. J\u2019ai v\u00e9cu mon enfance dans une famille proche de la nature. Petite, je r\u00eavais de devenir v\u00e9t\u00e9rinaire ou primatologue. Je suis devenue enseignant-chercheur, avant d\u2019accorder une plus grande place, en 2023, \u00e0 mon chemin photographique. Le fil conducteur de mes exp\u00e9riences est un int\u00e9r\u00eat tr\u00e8s fort pour la m\u00e9diation (artistique, animale, sociale) et la valorisation du patrimoine sous toutes ces formes.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><strong>&#8211; Quand et comment as-tu d\u00e9but\u00e9 en photo\u202f? Qu\u2019est-ce qu\u2019elle repr\u00e9sente pour toi\u202f?<\/strong><\/em><br>L\u2019Anjou, o\u00f9 j\u2019ai v\u00e9cu de 2016 \u00e0 2021, a \u00e9t\u00e9 le berceau de ma pratique photographique. Dot\u00e9es de nombreux cours d\u2019eau, de multiples zones humides et r\u00e9serves ornithologiques, les basses vall\u00e9es angevines ont constitu\u00e9 un terrain de contemplation privil\u00e9gi\u00e9. De retour en Bourgogne-Franche Comt\u00e9, la photographie m\u2019a permis de red\u00e9couvrir le patrimoine naturel de ce magnifique territoire, plus particuli\u00e8rement, de la vall\u00e9e de l\u2019Ouche, des vals Suzon et de Sa\u00f4ne, de l\u2019Auxois, du Morvan et de la for\u00eat de C\u00eeteaux, \u00e0 proximit\u00e9 de chez moi. La photographie correspond \u00e0 un d\u00e9sir personnel profond de d\u00e9connexion d\u2019un quotidien fortement affect\u00e9 par un handicap, de reconnexion \u00e0 mes \u00e9motions et \u00e0 mon environnement, et de partage d\u2019un \u00e9merveillement devant la biodiversit\u00e9 qui nous entoure.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>&#8211; De quoi parle ton exposition ?<\/em>&nbsp;<\/strong><br>\u00ab Tournesolation \u00bb est une s\u00e9rie photographique compos\u00e9e de 10 images qui mobilisent les techniques de double exposition et flou de bouger volontaire pour \u00e9voquer les effets des canicules et des fortes s\u00e9cheresses sur la vision de l\u2019objet photographi\u00e9 (symbolique, incandescent et m\u00e9taphysique), ainsi que sur celle du photographe (trouble, onirique, presque d\u00e9mente). C\u2019est une s\u00e9rie r\u00e9alis\u00e9e totalement statique devant un unique champ au cours d\u2019une m\u00eame fin de journ\u00e9e caniculaire et orageuse qui s\u2019est achev\u00e9e par une insolation. Le titre comporte la trace humoristique de cette anecdote.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>&#8211; En g\u00e9n\u00e9ral, quels sont les sujets qui t\u2019int\u00e9ressent\u202f? Qu\u2019est-ce que tu y cherches, y trouves\u202f?<\/em>&nbsp;<\/strong><br>J\u2019aime autant l\u2019approche naturaliste de sc\u00e8nes de vie ordinaires de la faune et de la flore locale, qu\u2019une approche macro ou proxy cr\u00e9ative pour cr\u00e9er des atmosph\u00e8res champ\u00eatres ou foresti\u00e8res oniriques. J\u2019essaie de transmettre la sensation de douceur, d\u2019apaisement ou d\u2019\u00e9vasion que je peux ressentir devant ces sujets. J\u2019aime \u00e9galement saisir et valoriser le mouvement et le geste. C\u2019est pourquoi j\u2019appr\u00e9cie aussi beaucoup de photographier le spectacle vivant ou encore les m\u00e9tiers d\u2019art et d\u2019artisanat.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><i><strong>-Lien hypertexte vers le site internet o\u00f9 l\u2019on peut te retrouver <\/strong>: <\/i><br><a href=\"https:\/\/www.elodiejarrier.com\">https:\/\/www.elodiejarrier.com<\/a> &amp; <a href=\"https:\/\/www.instagram.com\/elodie_jarrier\/\">Instagram<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature-683x1024.jpg\" alt=\"\" class=\"wp-image-17158\" srcset=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature-683x1024.jpg 683w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature-200x300.jpg 200w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature-768x1152.jpg 768w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature-1024x1536.jpg 1024w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature.jpg 1365w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Bandeau-sponsors-2025-828-x-315.jpg\"><img decoding=\"async\" width=\"828\" height=\"315\" src=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Bandeau-sponsors-2025-828-x-315.jpg\" alt=\"\" class=\"wp-image-17386\" srcset=\"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Bandeau-sponsors-2025-828-x-315.jpg 828w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Bandeau-sponsors-2025-828-x-315-300x114.jpg 300w, https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Bandeau-sponsors-2025-828-x-315-768x292.jpg 768w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Exposition aux Invit\u00e9s au festin, du 4 au 26 octobre Du lundi au vendredi de 13h30 \u00e0 16h30Dimanche 4, 11 et 25 octobre de 14h00 \u00e0 16h00 &#8211; Quelques mots [&hellip;]<\/p>\n","protected":false},"author":76,"featured_media":17158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[262,264],"tags":[],"class_list":["post-17214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival-2025-festival","category-interviews-2025"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/grain-dpixel.fr\/info\/wp-content\/uploads\/2025\/08\/Elodie-JARRIER-Photo-signature.jpg","_links":{"self":[{"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/posts\/17214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/comments?post=17214"}],"version-history":[{"count":4,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/posts\/17214\/revisions"}],"predecessor-version":[{"id":17402,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/posts\/17214\/revisions\/17402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/media\/17158"}],"wp:attachment":[{"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/media?parent=17214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/categories?post=17214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grain-dpixel.fr\/info\/wp-json\/wp\/v2\/tags?post=17214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}